{"id":13289,"date":"2020-05-20T19:00:40","date_gmt":"2020-05-20T19:00:40","guid":{"rendered":"https:\/\/jardineriepuig.fr\/fly-tying-le-pmot-skyaboveus\/"},"modified":"2020-06-02T15:02:48","modified_gmt":"2020-06-02T15:02:48","slug":"fly-tying-le-pmot-skyaboveus","status":"publish","type":"post","link":"https:\/\/jardineriepuig.fr\/it\/volare-legare-le-pmot-skyaboveus\/","title":{"rendered":"La tecnica della mosca: il PMOT"},"content":{"rendered":"<p>&nbsp;<\/p>\n<div id=\"mod_45724526\">\n<h2 class=\"subtitle\">N\u00e9 de la frustration &#8230; Le \u00ab\u00a0PMOT\u00a0\u00bb!<\/h2>\n<div id=\"txtd_45724526\" class=\"txtd\">\n<p>Le Purple Marabou and Orange Thing ou \u00ab\u00a0PMOT\u00a0\u00bb est une mouche de p\u00eache qui cible le bar achigan \u00e0 grande bouche. Il est n\u00e9 de la frustration lorsque la basse avait tendance \u00e0 ne pas mordre!.<\/p>\n<p>Au printemps, le frai de l&rsquo;achigan \u00e0 grande bouche suit. Souvent, en marchant doucement le long des rives de nos \u00e9tangs pr\u00e9f\u00e9r\u00e9s, nous avons observ\u00e9 des bars reposant sur leurs lits pr\u00eats \u00e0 chasser des personnages suspects comme d&rsquo;autres poissons, un crawdad ou une mouche de p\u00eache!<\/p>\n<blockquote><p>Scoprite il nuovo concetto <a href=\"https:\/\/jardineriepuig.fr\/it\/il-test-di-recensione-della-scatola-del-pescatore\/\">La scatola Fisher =&gt; la scatola 100% p\u00eache<\/a><\/p><\/blockquote>\n<p>Une mouche de p\u00eache particuli\u00e8re qui a \u00e9t\u00e9 efficace pour l&rsquo;achigan est la mouche de la demoiselle COAF. Le bar frappait lorsque la mouche de la p\u00eache passait devant son lit avec un arr\u00eat et un d\u00e9part. C&rsquo;\u00e9tait formidable lorsque les basses \u00e9taient agressives et facilement frapp\u00e9es par cette \u00ab\u00a0menace\u00a0\u00bb passag\u00e8re pour leurs nids.<\/p>\n<p>Cependant, lorsque la basse h\u00e9sitait et se m\u00e9fiait de frapper, une approche plus lente et plus prudente \u00e9tait n\u00e9cessaire. En jetant un coup d&rsquo;\u0153il \u00e0 la basse, nous d\u00e9posions la mouche de la demoiselle dans leurs lits et la secouions l\u00e9g\u00e8rement.<\/p>\n<p>Nous ferions cela jusqu&rsquo;\u00e0 ce que la basse frappe. Parfois, nous devions refaire plusieurs fois ce qui \u00e9tait le cas. C&rsquo;est pire quand une basse de cinq livres regarde votre mouche de p\u00eache, m\u00eame la mordille, mais d\u00e9cide de ne pas frapper &#8230; Frustration!<\/p>\n<p>Pour att\u00e9nuer notre frustration, nous avons d\u00e9velopp\u00e9 le Purple Marabou and Orange Thing ou \u00ab\u00a0PMOT\u00a0\u00bb.<\/p>\n<p>Il utilise un mat\u00e9riau minimal, est simple et rapide \u00e0 nouer, et repose avec des plumes de marabout flottant vers le haut tandis que la t\u00eate de la cha\u00eene de perles repose sur le fond.<\/p>\n<p>Lorsqu&rsquo;il est d\u00e9pos\u00e9 dans un lit Bass, le PMOT peut \u00eatre autoris\u00e9 \u00e0 s&rsquo;asseoir o\u00f9 il atterrit en restant dans la zone de frappe pendant de longues p\u00e9riodes.<\/p>\n<p>Pas besoin de refonte; au lieu de cela, laissez le PMOT reposer sur le fond. Ensuite, donnez-lui un l\u00e9ger mouvement pour donner du mouvement. Sinon, laissez-le tranquille et laissez les plumes se balancer de mani\u00e8re s\u00e9duisante \u00e0 la basse!<\/p>\n<p>Pour savoir comment attacher le \u00ab\u00a0PMOT\u00a0\u00bb, lisez la suite!<\/p>\n<\/div>\n<\/div>\n<div id=\"mod_45724527\">\n<h2 class=\"subtitle\"><span class=\"ez-toc-section\" id=\"Materiaux\"><\/span>Materiali<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<div id=\"txtd_45724527\" class=\"txtd\">\n<p>Voici la liste des mat\u00e9riaux pour le PMOT:<\/p>\n<ol>\n<li>Gancio per razzi taglia 8<\/li>\n<li>Due piume di marab\u00f9 viola<\/li>\n<li>Fil \u00e0 nouer orange Dacron 6\/0<\/li>\n<li>Oeil de cha\u00eene de perles<\/li>\n<li>Colle UV et lampe \u00e0 polym\u00e9riser<\/li>\n<\/ol>\n<\/div>\n<\/div>\n<div id=\"mod_45724529\">\n<h2 class=\"subtitle\">\u00c9tape 1 &#8211; Construisez la base du fil<\/h2>\n<div id=\"txtd_45724529\" class=\"txtd\">\n<p>Tout d&rsquo;abord, construisez la base du fil \u00e0 l&rsquo;aide du fil de liaison orange Dacron:<\/p>\n<ul>\n<li>Commencez \u00e0 envelopper une base de fil comme vous le feriez normalement lorsque vous attachez une mouche de p\u00eache.<\/li>\n<li>Arr\u00eatez le film \u00e0 environ 1\/4 \u00ab\u00a0de l&rsquo;\u0153illet du crochet.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<div id=\"mod_45724531\">\n<h2 class=\"subtitle\">\u00c9tape 2 &#8211; Oeil de cha\u00eene de perles<\/h2>\n<div id=\"txtd_45724531\" class=\"txtd\">\n<p>\u00c0 l&rsquo;\u00e9tape 2, l&rsquo;\u0153il de cha\u00eene de perles est ajout\u00e9:<\/p>\n<ul>\n<li>Placez l&rsquo;\u0153illet de cha\u00eene de perles \u00e0 l&rsquo;endroit o\u00f9 vous avez laiss\u00e9 le fil \u00e0 l&rsquo;\u00e9tape 1, \u00e0 environ 1\/4 \u00ab\u00a0de l&rsquo;\u0153illet de crochet.<\/li>\n<li>Fixez avec des enveloppes crois\u00e9es et terminez avec des enveloppes en huit.<\/li>\n<li>Une fois fix\u00e9, continuez \u00e0 enrouler le fil vers l&rsquo;arri\u00e8re le long de la tige du crochet vers le coude du crochet, en s&rsquo;arr\u00eatant \u00e0 environ 1\/4 \u00ab\u00a0de l&rsquo;\u0153illet de la cha\u00eene de perles.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<div id=\"mod_45724533\">\n<h2 class=\"subtitle\">\u00c9tape 3 &#8211; Application de colle UV<\/h2>\n<div id=\"txtd_45724533\" class=\"txtd\">\n<p>\u00c0 l&rsquo;\u00e9tape 3, le fil s&rsquo;enroule autour de l&rsquo;\u0153illet de la cha\u00eene de perles et le long de la tige du crochet sont coll\u00e9s \u00e0 l&rsquo;aide d&rsquo;une colle UV de votre pr\u00e9f\u00e9rence. La colle UV est utilis\u00e9e dans cette \u00e9tape en raison de sa r\u00e9sistance et de sa capacit\u00e9 de s\u00e9chage rapide!<\/p>\n<ul>\n<li>Appliquez de la colle UV sur les enroulements de fil de l&rsquo;\u0153il de la cha\u00eene de perles.<\/li>\n<li>Faites de m\u00eame pour les fils enroul\u00e9s le long du haut de la tige du crochet,<\/li>\n<li>Et puis, en retournant la mouche de p\u00eache, appliquez de la colle UV le long du bas de la tige du crochet.<\/li>\n<li>Polimerizza la colla UV in direzione del segno.<\/li>\n<\/ul>\n<p><em>Remarque: la colle UV utilis\u00e9e pour cet article \u00e9tait \u00ab\u00a05-Second Fix\u00a0\u00bb. Il comprend une lampe \u00e0 polym\u00e9riser LED UV int\u00e9gr\u00e9e et peut \u00eatre facilement achet\u00e9e chez Walmart, CVS Drug Store ou en ligne (voir ci-dessous).<\/em><\/p>\n<\/div>\n<\/div>\n<div id=\"mod_45724535\">\n<h2 class=\"subtitle\">\u00c9tape 4 &#8211; Ajouter Marabou Plume # 1<\/h2>\n<div id=\"txtd_45724535\" class=\"txtd\">\n<p>Pour l&rsquo;\u00e9tape 4, le premier panache de marabout est attach\u00e9 comme suit:<\/p>\n<ul>\n<li>Retirez le crochet de l&rsquo;\u00e9tau d&rsquo;attache de mouche, retournez-le de sorte que le coude du crochet remonte, puis fixez-le dans l&rsquo;\u00e9tau d&rsquo;attache de mouche.<\/li>\n<li>Placer le panache de marabout sur la tige du crochet juste apr\u00e8s le point m\u00e9dian tendant davantage vers la direction du coude du crochet.<\/li>\n<li>Fixez avec des enroulements de fil, coupez l&rsquo;extr\u00e9mit\u00e9 bout \u00e0 bout et continuez sur l&rsquo;extr\u00e9mit\u00e9 bout \u00e0 bout avec des enroulements de fil suppl\u00e9mentaires.<\/li>\n<li>Arr\u00eatez les enroulements de fil au milieu de la tige du crochet qui doit \u00eatre en avant du panache de marabout.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<div id=\"mod_45724537\">\n<h2 class=\"subtitle\">\u00c9tape 5 &#8211; Ajoutez Marabou Plume # 2 et construisez le corps<\/h2>\n<div id=\"txtd_45724537\" class=\"txtd\">\n<p>\u00c0 l&rsquo;\u00e9tape 5, le deuxi\u00e8me panache de marabout est ajout\u00e9, le corps est construit \u00e0 l&rsquo;aide du fil de liage.<\/p>\n<ul>\n<li>Posizionare il pennacchio di marab\u00f9 sul gambo dell'amo al centro e fissarlo con il filo.<\/li>\n<li>Ensuite, coupez le bout comme \u00e0 l&rsquo;\u00e9tape pr\u00e9c\u00e9dente, puis commencez \u00e0 construire le corps \u00e0 l&rsquo;aide du fil de liage.<\/li>\n<li>Construisez le corps de fa\u00e7on \u00e0 ce qu&rsquo;il soit l\u00e9g\u00e8rement inf\u00e9rieur \u00e0 1\/4 \u00ab\u00a0d&rsquo;\u00e9paisseur au maximum, puis arr\u00eatez le fil d&rsquo;attache en avant de l&rsquo;\u0153il de la cha\u00eene de perles.<\/li>\n<li>Appliquez un fini fouet, puis passez \u00e0 l&rsquo;\u00e9tape finale!<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<div id=\"mod_45724539\">\n<h2 class=\"subtitle\">\u00c9tape 6 &#8211; Plus de colle UV!<\/h2>\n<div id=\"txtd_45724539\" class=\"txtd\">\n<p>L&rsquo;\u00e9tape 6 est la derni\u00e8re \u00e9tape! Il faut appliquer plus de colle UV sur la mouche de p\u00eache.<\/p>\n<ul>\n<li>Appliquez de la colle UV sur la t\u00eate et le corps.<\/li>\n<li>Retournez la mouche de p\u00eache et appliquez de la colle UV sur la face inf\u00e9rieure.<\/li>\n<li>Cure comme avant &#8230; selon les instructions de la marque.<\/li>\n<\/ul>\n<p>Tout est fait &#8230; Il est temps d&rsquo;aller p\u00eacher!<\/p>\n<\/div>\n<\/div>\n<div id=\"mod_45724547\">\n<h2 class=\"subtitle\"><span class=\"ez-toc-section\" id=\"Suggestions\"><\/span>Suggerimenti<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<div id=\"txtd_45724547\" class=\"txtd\">\n<p>Lorsque vous p\u00eachez le PMOT, voici quelques suggestions de l&rsquo;\u00e9quipe de terrain du COAF!<\/p>\n<ul>\n<li>Apr\u00e8s avoir lanc\u00e9 le PMOT, laissez la mouche de p\u00eache reposer sans \u00eatre d\u00e9rang\u00e9e. Comptez jusqu&rsquo;\u00e0 dix, puis secouez la tige pour sauter la mouche du fond. Faites une pause pour un autre compte de dix, puis r\u00e9p\u00e9tez. Pr\u00e9parez-vous \u00e0 ce que la ligne se tende lorsque la basse prend la mouche de p\u00eache lorsqu&rsquo;elle repose sur le fond.<\/li>\n<li>Ajustez le nombre entre les secousses en fonction de l&rsquo;agressivit\u00e9 de la basse. Si les basses frappent peu apr\u00e8s que le PMOT ait atterri dans l&rsquo;eau, faites tomber le nombre \u00e0 5 ou moins. Si les basses frappent l\u00e9g\u00e8rement bien apr\u00e8s le compte \u00e0 10, augmentez le compte par incr\u00e9ments de 5 jusqu&rsquo;\u00e0 ce que vous trouviez le motif.<\/li>\n<li>Si l&rsquo;achigan poursuit activement les poissons-app\u00e2ts, renoncez au comptage et utilisez de courtes tractions sur la ligne de mouche. Portez des lunettes de soleil polaris\u00e9es et soyez \u00e0 l&rsquo;aff\u00fbt d&rsquo;une basse qui suit votre mouche de p\u00eache.<\/li>\n<li>Lorsque l&rsquo;achigan a commenc\u00e9 \u00e0 se reproduire et prot\u00e8ge ses lits, laissez tomber le PMOT juste devant le lit, puis travaillez-le le long du bas jusqu&rsquo;au bord du lit. Ensuite, laissez le PMOT s&rsquo;asseoir et, portant vos lunettes polaris\u00e9es, surveillez la r\u00e9action des basses.<\/li>\n<li>Si la basse l&rsquo;ignore, secouez la pointe de votre tige pour faire palpiter les panaches de marabout. Si la basse ne frappe pas, faites glisser lentement le PMOT de quelques pouces de plus dans le lit et r\u00e9p\u00e9tez. Soyez diligent et pr\u00e9parez-vous \u00e0 r\u00e9gler le crochet si vous perdez de vue le PMOT.<\/li>\n<li>Si la basse continue de l&rsquo;ignorer, d\u00e9placez-vous vers un autre emplacement et laissez la basse reposer. Mais revenez plus tard dans la journ\u00e9e ou le lendemain matin.<\/li>\n<\/ul>\n<p>Buona fortuna e buona pesca!<\/p>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>&nbsp; N\u00e9 de la frustration &#8230; Le \u00ab\u00a0PMOT\u00a0\u00bb! Le Purple Marabou and Orange Thing ou \u00ab\u00a0PMOT\u00a0\u00bb est une mouche de p\u00eache qui cible le bar achigan \u00e0 grande bouche. Il est n\u00e9 de la frustration lorsque la basse avait tendance \u00e0 ne pas mordre!. Au printemps, le frai de l&rsquo;achigan \u00e0 grande bouche suit. Souvent,&hellip;&nbsp;<a href=\"https:\/\/jardineriepuig.fr\/it\/volare-legare-le-pmot-skyaboveus\/\" rel=\"bookmark\">Leggi tutto \u00bb<span class=\"screen-reader-text\">La tecnica della mosca: il PMOT<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":13290,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[37],"tags":[],"class_list":["post-13289","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conseil-peche"],"wppr_data":[],"_links":{"self":[{"href":"https:\/\/jardineriepuig.fr\/it\/wp-json\/wp\/v2\/posts\/13289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jardineriepuig.fr\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jardineriepuig.fr\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jardineriepuig.fr\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jardineriepuig.fr\/it\/wp-json\/wp\/v2\/comments?post=13289"}],"version-history":[{"count":2,"href":"https:\/\/jardineriepuig.fr\/it\/wp-json\/wp\/v2\/posts\/13289\/revisions"}],"predecessor-version":[{"id":13575,"href":"https:\/\/jardineriepuig.fr\/it\/wp-json\/wp\/v2\/posts\/13289\/revisions\/13575"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jardineriepuig.fr\/it\/wp-json\/wp\/v2\/media\/13290"}],"wp:attachment":[{"href":"https:\/\/jardineriepuig.fr\/it\/wp-json\/wp\/v2\/media?parent=13289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jardineriepuig.fr\/it\/wp-json\/wp\/v2\/categories?post=13289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jardineriepuig.fr\/it\/wp-json\/wp\/v2\/tags?post=13289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}